{"id":1207,"date":"2016-01-13T13:25:51","date_gmt":"2016-01-13T12:25:51","guid":{"rendered":"http:\/\/www.tiendashoke.es\/blog\/?p=1207"},"modified":"2023-11-06T16:17:36","modified_gmt":"2023-11-06T15:17:36","slug":"correa-511-tactical-vtacs","status":"publish","type":"post","link":"https:\/\/www.tiendashoke.es\/blog\/correa-511-tactical-vtacs\/","title":{"rendered":"Correa 5.11 Tactical VTACS"},"content":{"rendered":"<p>Hoy os presentamos otro de los accesorios fundamentales, la <a href=\"https:\/\/www.tiendashoke.es\/correas-para-armas\/correa-511-vtac-bungee?utm_source=articulos&amp;utm_medium=enlaces&amp;utm_campaign=contenidos\" target=\"_blank\" rel=\"noopener noreferrer\">correa 5.11 Tactical VTACS<\/a> para nuestra r\u00e9plica. En este caso os traemos la marca 5.11, evidentemente como podr\u00e9is comprobar esta marca est\u00e1 pensada para su uso en armas reales, por lo que su calidad es excepcional a la par que sube su precio. Pero aun as\u00ed los rifles de airsoft en muchos casos no son precisamente baratos, por lo que si vamos a jugar con un rifle en el que hemos invertido mucho dinero, deber\u00edamos asegurar dicha inversi\u00f3n con una buena correa que nos garantice la m\u00e1xima fiabilidad frente a roturas.<\/p>\n<p>En 5.11 disponen de dos modelos para la versi\u00f3n de un punto, la versi\u00f3n el\u00e1stica que es la que vamos a analizar y la versi\u00f3n \u201cest\u00e1tica\u201d. La \u00fanica diferencia es que la est\u00e1tica no dispone del tramo el\u00e1stico final.<\/p>\n<p><iframe title=\"YouTube video player\" data-src=\"https:\/\/www.youtube.com\/embed\/--4NPTNnklo\" width=\"100%\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>Entrando ya en el an\u00e1lisis podemos comentar que est\u00e1 fabricada en 100% Nylon 500D, proporcion\u00e1ndonos la m\u00e1xima resistencia y fiabilidad.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-3240 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa1-1-150x150.jpg\" alt=\"Correa 5.11 Tactical bungee\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><img decoding=\"async\" class=\"wp-image-3239 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa5-1-150x150.jpg\" alt=\"Portafusil 5.11 tacticatl Viking tactics\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/p>\n<p>Esta versi\u00f3n viene con un extremo el\u00e1stico, el cual nos permite amortiguar el efecto causado al soltar el rifle y as\u00ed evitar en la mayor medida posible el deterioro del cierre (cosa que no pasa en la versi\u00f3n est\u00e1tica).\u00a0A parte de la correa viene con tres accesorios extra que nos permite extender la longitud de la correa, o adaptarla a la culata del rifle con un sistema de anclaje diferente.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-3237 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa3-1-150x150.jpg\" alt=\"Accesorios correa 5.11 Vtacs\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/p>\n<div id=\"attachment_1242\" style=\"width: 160px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa16.jpg\"><img decoding=\"async\" aria-describedby=\"caption-attachment-1242\" class=\"wp-image-1242 size-thumbnail lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa16-150x150.jpg\" alt=\"Anclaje correa 5.11 Tactical\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/a><p id=\"caption-attachment-1242\" class=\"wp-caption-text\">Anclaje correa 5.11 Tactical<\/p><\/div>\n<p style=\"text-align: left;\">Adem\u00e1s de poder regular su longitud mediante la hebilla de la imagen.\u00a0Tambi\u00e9n mencionar la calidad\u00a0 y resistencia de las costuras por toda la correa.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-3235 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa7-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><img decoding=\"async\" class=\"wp-image-3234 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa15-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><img decoding=\"async\" class=\"wp-image-3232 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa4-1-150x150.jpg\" alt=\"Costuras correa 5.11 tactical Vtacs\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/p>\n<p>Sistema de aperturaEl anclaje que tiene es de acero inoxidable, adem\u00e1s lleva incorporado un sistema de apertura r\u00e1pida. B\u00e1sicamente tirando del cord\u00f3n liberaremos el pasador que mantiene cerrado el enganche.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-3229 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa10-1-150x150.jpg\" alt=\"Detalle de la correa de anclaje de 5.11 Tactical\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/p>\n<p>Anclaje correa 5.11 tactical<img decoding=\"async\" class=\"wp-image-3227 size-thumbnail alignleft lazyload\" data-src=\"https:\/\/www.tiendashoke.es\/blog\/wp-content\/uploads\/5.11correa141-1-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" title=\"\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 150px; --smush-placeholder-aspect-ratio: 150\/150;\"><\/p>\n<p>Comentar tambi\u00e9n que est\u00e1 disponible en dos colores: negro y Sandstone.<\/p>\n<p>Finalmente comentar que est\u00e1 disponible con los siguientes precios:<\/p>\n<ul>\n<li>Versi\u00f3n el\u00e1stica: 49,95\u20ac<\/li>\n<li>Versi\u00f3n est\u00e1tica: 44,95\u20ac<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Hoy os presentamos otro de los accesorios fundamentales, la correa 5.11 Tactical VTACS para nuestra r\u00e9plica. En este caso os traemos la marca 5.11, evidentemente como podr\u00e9is comprobar esta marca est\u00e1 pensada para su uso en armas reales, por lo que su calidad es excepcional a la par que sube su precio. Pero aun as\u00ed los rifles de airsoft en muchos casos no son precisamente baratos, por lo que si vamos a jugar con un rifle en el que hemos invertido mucho dinero, deber\u00edamos asegurar dicha inversi\u00f3n con una buena correa que nos garantice la m\u00e1xima fiabilidad frente a roturas. En 5.11 disponen de dos modelos para la versi\u00f3n de un punto, la versi\u00f3n el\u00e1stica que es la que vamos a analizar y la versi\u00f3n \u201cest\u00e1tica\u201d. La \u00fanica diferencia es que la est\u00e1tica no dispone del tramo el\u00e1stico final. Entrando ya en el an\u00e1lisis podemos comentar que est\u00e1 fabricada en 100% Nylon 500D, proporcion\u00e1ndonos la m\u00e1xima resistencia y fiabilidad. Esta versi\u00f3n viene con un extremo el\u00e1stico, el cual nos permite amortiguar el efecto causado al soltar el rifle y as\u00ed evitar en la mayor medida posible el deterioro del cierre (cosa que no pasa en la versi\u00f3n est\u00e1tica).\u00a0A parte de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-material-policial"],"_links":{"self":[{"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/posts\/1207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/comments?post=1207"}],"version-history":[{"count":0,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/posts\/1207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/media\/1242"}],"wp:attachment":[{"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/media?parent=1207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/categories?post=1207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tiendashoke.es\/blog\/wp-json\/wp\/v2\/tags?post=1207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}